{"id":242906,"date":"2016-02-17T23:27:03","date_gmt":"2016-02-17T21:27:03","guid":{"rendered":"https:\/\/beecare.ch\/?page_id=242906"},"modified":"2026-01-21T15:45:02","modified_gmt":"2026-01-21T13:45:02","slug":"fragen-und-antworten-2","status":"publish","type":"page","link":"https:\/\/beecare.ch\/de\/fragen-und-antworten-2\/","title":{"rendered":"Fragen und Antworten"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"242906\" class=\"elementor elementor-242906 elementor-91\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6751afb2 elementor-section-height-min-height elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-items-middle wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"6751afb2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-563cb9d0\" data-id=\"563cb9d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6084d91 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"6084d91\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewBox=\"0 0 64 64\" xml:space=\"preserve\"><g id=\"Grids\" display=\"none\">\t<g id=\"Grid_72_\" display=\"inline\">\t\t<g>\t\t\t<path fill=\"#FF0000\" d=\"M51.9,4.1v55.8H12.1V4.1H51.9 M52,4H12v56h40V4L52,4z\"><\/path>\t\t<\/g>\t\t<g>\t\t\t<path fill=\"#4600F0\" d=\"M59.9,12.1v39.8H4.1V12.1H59.9 M60,12H4v40h56V12L60,12z\"><\/path>\t\t<\/g>\t\t<g>\t\t\t<path fill=\"#F0C800\" d=\"M55.9,8.1v47.8H8.1V8.1H55.9 M56,8H8v48h48V8L56,8z\"><\/path>\t\t<\/g>\t\t<g>\t\t\t<path fill=\"#00F096\" d=\"M32,6.1c14.281,0,25.9,11.619,25.9,25.9S46.281,57.9,32,57.9S6.1,46.281,6.1,32S17.719,6.1,32,6.1 M32,6    C17.641,6,6,17.641,6,32s11.641,26,26,26s26-11.641,26-26S46.359,6,32,6L32,6z\"><\/path>\t\t<\/g>\t<\/g><\/g><g id=\"Captions\">\t<g>\t<\/g><\/g><g id=\"Icons\">\t<g>\t\t<path d=\"M14,58.5h30.34v-1H14c-0.827,0-1.5-0.673-1.5-1.5V6c0-0.827,0.673-1.5,1.5-1.5h36c0.827,0,1.5,0.673,1.5,1.5v48.34h1V6   c0-1.379-1.121-2.5-2.5-2.5H14c-1.378,0-2.5,1.121-2.5,2.5v50C11.5,57.379,12.622,58.5,14,58.5z\"><\/path>\t\t<path d=\"M17,12.5h7v-1h-7c-0.827,0-1.5,0.673-1.5,1.5v40c0,0.827,0.673,1.5,1.5,1.5h23.34v-1H17c-0.276,0-0.5-0.225-0.5-0.5V13   C16.5,12.725,16.724,12.5,17,12.5z\"><\/path>\t\t<path d=\"M48.5,50.34V13c0-0.827-0.673-1.5-1.5-1.5h-7v1h7c0.275,0,0.5,0.225,0.5,0.5v37.34H48.5z\"><\/path>\t\t<path d=\"M28,14h8c1.1,0,2-0.9,2-2v-1.5h1c0.827,0,1.5-0.673,1.5-1.5V7c0-0.827-0.673-1.5-1.5-1.5H25c-0.827,0-1.5,0.673-1.5,1.5v2   c0,0.827,0.673,1.5,1.5,1.5h1V12C26,13.1,26.9,14,28,14z M37,12c0,0.55-0.45,1-1,1h-8c-0.55,0-1-0.45-1-1v-1.5h10V12z M25,9.5   c-0.276,0-0.5-0.225-0.5-0.5V7c0-0.275,0.224-0.5,0.5-0.5h14c0.275,0,0.5,0.225,0.5,0.5v2c0,0.275-0.225,0.5-0.5,0.5   C34.31,9.5,29.658,9.5,25,9.5z\"><\/path>\t\t<path d=\"M40.5,31.07V28.26c0.282,0.02,0.57-0.007,0.849-0.123c1.271-0.526,1.516-2.131,0.605-3.041l-9.344-9.344   c-0.337-0.334-0.883-0.334-1.222,0.001l-9.342,9.343c-0.903,0.9-0.678,2.509,0.605,3.042c0.328,0.135,0.571,0.152,0.848,0.133   v2.799h1v-3.187c0.062-0.049,0.126-0.094,0.183-0.151L32,20.416l7.316,7.316c0.056,0.056,0.123,0.09,0.184,0.137v3.201H40.5z    M32.354,19.355c-0.195-0.195-0.512-0.195-0.707,0l-7.67,7.67c-0.256,0.256-0.608,0.326-0.942,0.188   c-0.61-0.251-0.69-1.001-0.281-1.41L32,16.556l9.247,9.247c0.406,0.406,0.332,1.156-0.281,1.41   c-0.332,0.139-0.686,0.07-0.942-0.188L32.354,19.355z\"><\/path>\t\t<path d=\"M36.5,28.69v-1.7c0-0.827-0.673-1.5-1.5-1.5h-6c-0.827,0-1.5,0.673-1.5,1.5v1.7h1v-1.7c0-0.275,0.224-0.5,0.5-0.5h6   c0.275,0,0.5,0.225,0.5,0.5v1.7H36.5z\"><\/path>\t\t<path d=\"M32,31.5c-4.687,0-8.5,3.813-8.5,8.5s3.813,8.5,8.5,8.5c4.687,0,8.5-3.813,8.5-8.5S36.687,31.5,32,31.5z M32,47.5   c-4.136,0-7.5-3.364-7.5-7.5s3.364-7.5,7.5-7.5s7.5,3.364,7.5,7.5S36.136,47.5,32,47.5z\"><\/path>\t\t<path d=\"M51.839,56.304l-8.364-8.364c-0.458-0.458-1.137-0.544-1.692-0.284L40.4,46.273c1.312-1.753,2.1-3.92,2.1-6.273   c0-5.79-4.71-10.5-10.5-10.5c-5.79,0-10.5,4.71-10.5,10.5S26.21,50.5,32,50.5c2.353,0,4.521-0.787,6.273-2.1l1.382,1.382   c-0.26,0.556-0.174,1.234,0.284,1.693l8.364,8.364c0.965,0.967,2.549,0.987,3.535,0S52.806,57.268,51.839,56.304z M22.5,40   c0-5.238,4.262-9.5,9.5-9.5s9.5,4.262,9.5,9.5s-4.262,9.5-9.5,9.5S22.5,45.238,22.5,40z M39.761,47.048l1.242,1.242l-0.713,0.713   l-1.242-1.242C39.297,47.534,39.534,47.297,39.761,47.048z M51.132,59.132c-0.567,0.567-1.556,0.565-2.121,0l-8.364-8.364   c-0.195-0.195-0.195-0.512,0-0.707l1.414-1.414c0.195-0.195,0.512-0.195,0.707,0l8.364,8.364   C51.72,57.599,51.715,58.548,51.132,59.132z\"><\/path>\t\t<path d=\"M32.63,35.056c-2.164-0.389-4.13,1.269-4.13,3.444h1c0-1.498,1.337-2.743,2.958-2.46c1.002,0.177,1.826,1,2.002,2.002   c0.229,1.31-0.557,2.546-1.828,2.878c-0.677,0.177-1.132,0.74-1.132,1.403V43.5h1v-1.177c0-0.231,0.193-0.386,0.385-0.437   c1.779-0.463,2.88-2.19,2.56-4.018C35.197,36.46,34.04,35.303,32.63,35.056z\"><\/path>\t\t<rect x=\"31.5\" y=\"45\" width=\"1\" height=\"1\"><\/rect>\t<\/g><\/g><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59dc3904 elementor-widget elementor-widget-heading\" data-id=\"59dc3904\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Fragen und Antworten<\/h1>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-301c71a7 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"301c71a7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5d2356a4\" data-id=\"5d2356a4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a7d8f4 elementor-widget elementor-widget-toggle\" data-id=\"1a7d8f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2771\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2771\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> Wie kann ich auf die Dienstleistungen von BeeCare zugreife<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2771\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2771\"><p>Um unsere Dienstleistungen in Anspruch zu nehmen, f\u00fcllen Sie einfach das Formular auf unserer &#171;<a href=\"https:\/\/beecare.ch\/de\/kontakt\/\">Kontakt<\/a>&#171;-Seite aus und senden Sie die Anfrage oder kontaktieren Sie uns telefonisch an unseren Standorten.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2772\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2772\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Wie aktiviert man den Spitex-Service?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2772\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2772\"><p>Um die Dienstleistungen zu empfangen, setzen Sie sich einfach mit der angegebenen Adresse in Verbindung und vereinbaren Sie ein Treffen mit dem Gesundheitsleiter in Ihrem Haus. W\u00e4hrend dieser Sitzung wird das medizinische Fachpersonal Ihren Gesundheits- und Pflegebedarf bewerten und Modalit\u00e4ten f\u00fcr die Durchf\u00fchrung des Pflegeplans vorschlagen. Er erkl\u00e4rt Ihnen auch genau die Ziele und die Modalit\u00e4ten, wie die Leistungen durchf\u00fchrt werden.<\/p>\n<p>Die Angestellten sind f\u00fcr die T\u00e4tigkeiten qualifiziert und professionell geschult, die durchgef\u00fchrt werden m\u00fcssen. Der Zugang des Personals wird mit Ihnen festgelegt und findet durch einen vereinbarten Zeitplan statt.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2773\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2773\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Wer kommt zu mir nach Hause?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2773\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2773\"><p>In Ihrem Hause wird die geeignetste Gesundheitsbetreuung f\u00fcr Ihre Situation gesucht, zum Beispiel f\u00fcr die Pflege eine Krankenschwester, f\u00fcr die Grundversorgung einen Pflege-Assistenten.<\/p>\n<p>Alle unsere Mitarbeiter folgen den Anweisungen, die in Ihrem pers\u00f6nlichen Pflegeplan enthalten sind. Das Personal weisst sich aus, indem eine Identifikationskarte vorgezeigt wird.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2774\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2774\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u00dcbernimmt die Krankenversicherung die Kosten der Leistungen?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2774\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2774\"><p>Die Pflegeleistungen m\u00fcssen von Ihrem Arzt verschrieben werden, Ihre Krankenversicherung \u00fcbernimmt anschliessend die Kosten f\u00fcr die Leistungen der h\u00e4uslichen Pflege nach Artikel 7 \u201eKLV\u201c. Die Rechnung der obligatorischen Leistungen wird direkt an die Krankenversicherung weitergeleitet. Die nicht vorgesehenen Leistungen der KVG werden direkt dem Nutzer in Rechnung gestellt, der nach der Zahlung eine zus\u00e4tzliche R\u00fcckerstattung von der Krankenversicherung verlangen kann.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2775\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-2775\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Meine Schwester, 70 Jahre alt, ist ein Pflegefall, lebt mit mir bereits seit Jahren zusammen, ist zurzeit im Krankenhaus untergebracht und muss zu Hause eine Tropfinfusion fortsetzen. Wie k\u00f6nnen Sie mir helfen?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2775\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-2775\"><p>Es ist wichtig, einen Entlassungsbrief vom Krankenhaus mit den aktuellen therapeutischen Verschreibungen zu besitzen. Das Krankenhaus \u00fcbergibt eine Zusammenfassung \u00fcber die Bed\u00fcrfnisse der Person in Bezug auf die h\u00e4usliche Pflege.<\/p>\n<p>BeeCare wird mit dem Krankenhaus und dem Hausarzt in Kontakt treten und sich auf den Zeitpunkt der Entlassung beziehen, um eine Pflegeweiterf\u00fchrung zu gew\u00e4hrleisten. So ist der Gesundheitsleiter oder, in seiner Abwesenheit, die Krankenschwester im Hause, um pr\u00e4ventiv einen Termin f\u00fcr die Betreuung und nachfolgende Unterst\u00fctzung zu vereinbaren.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2776\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-2776\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ich bin eine Frau von 43 Jahren, ich habe mich durch einen Schl\u00fcsselbeinbruch verletzt, so dass ich nicht mehr selbstst\u00e4ndig unter die Dusche gehen kann. Ich lebe mit meiner Mutter zusammen, die sehr alt und nicht mehr in der Lage ist, mir zu helfen. Habe ich einen Anspruch auf Leistungen?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2776\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-2776\"><p>Als Folge Ihrer Verletzung und durch die funktionelle Einschr\u00e4nkung, unter der Sie leiden, haben Sie Anspruch auf Leistungen. Sie m\u00fcssen \u00fcber Ihren Arzt einen Antrag stellen. Anschliessend k\u00f6nnen Sie von den h\u00e4uslichen Unterst\u00fctzungs- und Pflegeleistungen f\u00fcr eine begrenzte Zeit oder bis zum Zeitpunkt der Heilung profitieren.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2777\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-2777\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ich kann meinen Vater nicht mehr allein lassen. Aufgrund seiner fortschreitenden Alzheimer-Krankheit wei\u00df er manchmal nicht, wo er sich befindet und wer er ist. Ich brauche eine kompetente, zuverl\u00e4ssige und erfahrene Hilfe, die den ganzen Tag bei meinem Vater bleibt, den Haushalt f\u00fchrt, ihm das Mittagessen zubereitet und mit ihm spazieren geht.<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2777\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-2777\"><p>Wir stellen Ihnen eine referenzierte Person als Bezugspunkt f\u00fcr Ihren Vater zur Verf\u00fcgung, die immer die gleiche ist und ihn \u00fcber die gew\u00fcnschte Anzahl Stunden am Tag oder auch den ganzen Tag betreut.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2778\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-2778\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Die kontinuierliche h\u00e4usliche Betreuung meines Vaters ist sehr kostenintensiv. Die Krankenversicherung deckt nur grundlegende Pflegeleistungen und medizinische Versorgung ab. Wie kann ich finanzielle Unterst\u00fctzung beantragen, um die Kosten f\u00fcr eine h\u00e4usliche Pflegekraft zu bew\u00e4ltigen?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2778\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-2778\"><p>Die Kosten f\u00fcr die h\u00e4usliche Betreuung \u00e4lterer Menschen k\u00f6nnen auch durch <strong>Wirtschaftshilfen der Konf\u00f6deration und des Kantons<\/strong> unterst\u00fctzt werden. Sie k\u00f6nnen \u00fcberpr\u00fcfen, welche Unterst\u00fctzung Sie in Anspruch nehmen k\u00f6nnen, indem Sie die zust\u00e4ndigen Stellen kontaktieren, wie zum Beispiel die Stiftung Pro Senectute. Einige wirtschaftliche Unterst\u00fctzungen werden aufgrund des Gesundheitszustands vergeben, wie zum Beispiel die Gro\u00dfe Invalidit\u00e4tsrente, w\u00e4hrend andere aufgrund der wirtschaftlichen Bedingungen vergeben werden. Au\u00dferdem gibt es viele erg\u00e4nzende Dienstleistungen wie Mahlzeitendienste und Tageszentren, die zur Aufrechterhaltung der h\u00e4uslichen Pflege \u00e4lterer Menschen beitragen. Um die Pflege am besten zu organisieren, sollten die zust\u00e4ndigen Stellen kontaktiert werden.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2779\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-2779\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Nach einem n\u00e4chtlichen Sturz im Bad hat meine Mutter nun Angst, nachts allein zu bleiben. Was kann ich tun? K\u00f6nnen Sie mir jemanden schicken, der jede Nacht bei meiner Mutter schl\u00e4ft?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2779\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-2779\"><p>Wir stellen Ihnen zwei Personen zur Verf\u00fcgung, die immer die gleichen sind und die abends um 20:00 zu Ihrer Mutter kommen und morgens um 08:00 wieder wegfahren. Auf diese Weise ist die Betreuung die ganze Nacht garantiert. Unser Personal schl\u00e4ft im Zimmer neben dem Schlafzimmer Ihrer Mutter. Bei Bedarf kann Ihre Mutter das Personal rufen, um sich helfen oder begleiten zu lassen.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-27710\" class=\"elementor-tab-title\" data-tab=\"10\" role=\"button\" aria-controls=\"elementor-tab-content-27710\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ich bin im 6. Monat schwanger. Aufgrund von Ischiasproblemen habe ich gro\u00dfe M\u00fche mit der Hausarbeit bei mir zu Hause. Kann ich eine Hilfe in Anspruch nehmen?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-27710\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"10\" role=\"region\" aria-labelledby=\"elementor-tab-title-27710\"><p>Ihr Gyn\u00e4kologe muss ein \u00e4rztliches Attest ausstellen, das eine Haushaltshilfe vorschreibt. Wenn Sie eine Zusatzversicherung abgeschlossen haben, ist diese Leistung hierdurch gedeckt. Wir stellen Ihnen eine Haushaltshilfe zur Verf\u00fcgung, die zwei oder drei Stunden pro Woche zum Saubermachen, W\u00e4schewaschen, B\u00fcgeln etc. zu Ihnen kommt.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-27711\" class=\"elementor-tab-title\" data-tab=\"11\" role=\"button\" aria-controls=\"elementor-tab-content-27711\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Mein Vater braucht eine h\u00e4usliche Blutentnahme, was muss ich vorbereiten?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-27711\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"11\" role=\"region\" aria-labelledby=\"elementor-tab-title-27711\"><p>Sie m\u00fcssen eine Auflagefl\u00e4che bereitstellen oder frei r\u00e4umen und es m\u00fcssen m\u00f6glicherweise die Anforderungen des Fastens eingehalten werden (die von der Krankenschwester oder dem Arzt hinsichtlich der durchzuf\u00fchrenden Untersuchungen angegeben werden). Tragen Sie bequeme Kleidung, um den Arm dort leicht freizumachen, wo die Entnahme durchgef\u00fchrt werden muss. Sorgen Sie f\u00fcr eine angemessene Beleuchtung des Raums.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3a56bda1 elementor-section-full_width elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"3a56bda1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-20b72ad8\" data-id=\"20b72ad8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e7fa6df elementor-widget elementor-widget-heading\" data-id=\"5e7fa6df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Haben Sie weitere Fragen?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72c14ece elementor-align-center elementor-widget elementor-widget-button\" data-id=\"72c14ece\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/beecare.ch\/de\/kontakt\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Kontakt<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>&nbsp; Fragen und Antworten Wie kann ich auf die Dienstleistungen von BeeCare zugreife Um unsere Dienstleistungen in Anspruch zu nehmen, f\u00fcllen Sie einfach das Formular auf unserer \u201cKontakt\u201c-Seite aus und senden Sie die Anfrage oder kontaktieren Sie uns telefonisch an unseren Standorten. Wie aktiviert man den Spitex-Service? Um die Dienstleistungen zu empfangen, setzen Sie sich einfach mit der angegebenen Adresse in Verbindung und vereinbaren Sie ein Treffen mit dem Gesundheitsleiter in Ihrem Haus. W\u00e4hrend dieser Sitzung wird das medizinische Fachpersonal Ihren Gesundheits- und Pflegebedarf bewerten und Modalit\u00e4ten f\u00fcr die Durchf\u00fchrung des Pflegeplans vorschlagen. Er erkl\u00e4rt Ihnen auch genau die Ziele und die Modalit\u00e4ten, wie die Leistungen durchf\u00fchrt werden. Die Angestellten sind f\u00fcr die T\u00e4tigkeiten qualifiziert und professionell geschult, die durchgef\u00fchrt werden m\u00fcssen. Der Zugang des Personals wird mit Ihnen festgelegt und findet durch einen vereinbarten Zeitplan statt. Wer kommt zu mir nach Hause? In Ihrem Hause wird die geeignetste Gesundheitsbetreuung f\u00fcr Ihre Situation gesucht, zum Beispiel f\u00fcr die Pflege eine Krankenschwester, f\u00fcr die Grundversorgung einen Pflege-Assistenten. Alle unsere Mitarbeiter folgen den Anweisungen, die in Ihrem pers\u00f6nlichen Pflegeplan enthalten sind. Das Personal weisst sich aus, indem eine Identifikationskarte vorgezeigt wird. \u00dcbernimmt die Krankenversicherung die Kosten der Leistungen? Die Pflegeleistungen m\u00fcssen von Ihrem Arzt verschrieben werden, Ihre Krankenversicherung \u00fcbernimmt anschliessend die Kosten f\u00fcr die Leistungen der h\u00e4uslichen Pflege nach Artikel 7 \u201eKLV\u201c. Die Rechnung der obligatorischen Leistungen wird direkt an die Krankenversicherung weitergeleitet. Die nicht vorgesehenen Leistungen der KVG werden direkt dem Nutzer in Rechnung gestellt, der nach der Zahlung eine zus\u00e4tzliche R\u00fcckerstattung von der Krankenversicherung verlangen kann. Meine Schwester, 70 Jahre alt, ist ein Pflegefall, lebt mit mir bereits seit Jahren zusammen, ist zurzeit im Krankenhaus untergebracht und muss zu Hause eine Tropfinfusion fortsetzen. Wie k\u00f6nnen Sie mir helfen? Es ist wichtig, einen Entlassungsbrief vom Krankenhaus mit den aktuellen therapeutischen Verschreibungen zu besitzen. Das Krankenhaus \u00fcbergibt eine Zusammenfassung \u00fcber die Bed\u00fcrfnisse der Person in Bezug auf die h\u00e4usliche Pflege. BeeCare wird mit dem Krankenhaus und dem Hausarzt in Kontakt treten und sich auf den Zeitpunkt der Entlassung beziehen, um eine Pflegeweiterf\u00fchrung zu gew\u00e4hrleisten. So ist der Gesundheitsleiter oder, in seiner Abwesenheit, die Krankenschwester im Hause, um pr\u00e4ventiv einen Termin f\u00fcr die Betreuung und nachfolgende Unterst\u00fctzung zu vereinbaren. Ich bin eine Frau von 43 Jahren, ich habe mich durch einen Schl\u00fcsselbeinbruch verletzt, so dass ich nicht mehr selbstst\u00e4ndig unter die Dusche gehen kann. Ich lebe mit meiner Mutter zusammen, die sehr alt und nicht mehr in der Lage ist, mir zu helfen. Habe ich einen Anspruch auf Leistungen? Als Folge Ihrer Verletzung und durch die funktionelle Einschr\u00e4nkung, unter der Sie leiden, haben Sie Anspruch auf Leistungen. Sie m\u00fcssen \u00fcber Ihren Arzt einen Antrag stellen. Anschliessend k\u00f6nnen Sie von den h\u00e4uslichen Unterst\u00fctzungs- und Pflegeleistungen f\u00fcr eine begrenzte Zeit oder bis zum Zeitpunkt der Heilung profitieren. Ich kann meinen Vater nicht mehr allein lassen. Aufgrund seiner fortschreitenden Alzheimer-Krankheit wei\u00df er manchmal nicht, wo er sich befindet und wer er ist. Ich brauche eine kompetente, zuverl\u00e4ssige und erfahrene Hilfe, die den ganzen Tag bei meinem Vater bleibt, den Haushalt f\u00fchrt, ihm das Mittagessen zubereitet und mit ihm spazieren geht. Wir stellen Ihnen eine referenzierte Person als Bezugspunkt f\u00fcr Ihren Vater zur Verf\u00fcgung, die immer die gleiche ist und ihn \u00fcber die gew\u00fcnschte Anzahl Stunden am Tag oder auch den ganzen Tag betreut. Die kontinuierliche h\u00e4usliche Betreuung meines Vaters ist sehr kostenintensiv. Die Krankenversicherung deckt nur grundlegende Pflegeleistungen und medizinische Versorgung ab. Wie kann ich finanzielle Unterst\u00fctzung beantragen, um die Kosten f\u00fcr eine h\u00e4usliche Pflegekraft zu bew\u00e4ltigen? Die Kosten f\u00fcr die h\u00e4usliche Betreuung \u00e4lterer Menschen k\u00f6nnen auch durch Wirtschaftshilfen der Konf\u00f6deration und des Kantons unterst\u00fctzt werden. Sie k\u00f6nnen \u00fcberpr\u00fcfen, welche Unterst\u00fctzung Sie in Anspruch nehmen k\u00f6nnen, indem Sie die zust\u00e4ndigen Stellen kontaktieren, wie zum Beispiel die Stiftung Pro Senectute. Einige wirtschaftliche Unterst\u00fctzungen werden aufgrund des Gesundheitszustands vergeben, wie zum Beispiel die Gro\u00dfe Invalidit\u00e4tsrente, w\u00e4hrend andere aufgrund der wirtschaftlichen Bedingungen vergeben werden. Au\u00dferdem gibt es viele erg\u00e4nzende Dienstleistungen wie Mahlzeitendienste und Tageszentren, die zur Aufrechterhaltung der h\u00e4uslichen Pflege \u00e4lterer Menschen beitragen. Um die Pflege am besten zu organisieren, sollten die zust\u00e4ndigen Stellen kontaktiert werden. Nach einem n\u00e4chtlichen Sturz im Bad hat meine Mutter nun Angst, nachts allein zu bleiben. Was kann ich tun? K\u00f6nnen Sie mir jemanden schicken, der jede Nacht bei meiner Mutter schl\u00e4ft? Wir stellen Ihnen zwei Personen zur Verf\u00fcgung, die immer die gleichen sind und die abends um 20:00 zu Ihrer Mutter kommen und morgens um 08:00 wieder wegfahren. Auf diese Weise ist die Betreuung die ganze Nacht garantiert. Unser Personal schl\u00e4ft im Zimmer neben dem Schlafzimmer Ihrer Mutter. Bei Bedarf kann Ihre Mutter das Personal rufen, um sich helfen oder begleiten zu lassen. Ich bin im 6. Monat schwanger. Aufgrund von Ischiasproblemen habe ich gro\u00dfe M\u00fche mit der Hausarbeit bei mir zu Hause. Kann ich eine Hilfe in Anspruch nehmen? Ihr Gyn\u00e4kologe muss ein \u00e4rztliches Attest ausstellen, das eine Haushaltshilfe vorschreibt. Wenn Sie eine Zusatzversicherung abgeschlossen haben, ist diese Leistung hierdurch gedeckt. Wir stellen Ihnen eine Haushaltshilfe zur Verf\u00fcgung, die zwei oder drei Stunden pro Woche zum Saubermachen, W\u00e4schewaschen, B\u00fcgeln etc. zu Ihnen kommt. Mein Vater braucht eine h\u00e4usliche Blutentnahme, was muss ich vorbereiten? Sie m\u00fcssen eine Auflagefl\u00e4che bereitstellen oder frei r\u00e4umen und es m\u00fcssen m\u00f6glicherweise die Anforderungen des Fastens eingehalten werden (die von der Krankenschwester oder dem Arzt hinsichtlich der durchzuf\u00fchrenden Untersuchungen angegeben werden). Tragen Sie bequeme Kleidung, um den Arm dort leicht freizumachen, wo die Entnahme durchgef\u00fchrt werden muss. Sorgen Sie f\u00fcr eine angemessene Beleuchtung des Raums. Haben Sie weitere Fragen? Kontakt<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"elementor_header_footer","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","inline_featured_image":false,"_mbp_gutenberg_autopost":false,"_pgmb_is_evergreen":true,"_pgmb_ap_template_id":0,"footnotes":""},"class_list":["post-242906","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/beecare.ch\/de\/wp-json\/wp\/v2\/pages\/242906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beecare.ch\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/beecare.ch\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/beecare.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/beecare.ch\/de\/wp-json\/wp\/v2\/comments?post=242906"}],"version-history":[{"count":1,"href":"https:\/\/beecare.ch\/de\/wp-json\/wp\/v2\/pages\/242906\/revisions"}],"predecessor-version":[{"id":253008,"href":"https:\/\/beecare.ch\/de\/wp-json\/wp\/v2\/pages\/242906\/revisions\/253008"}],"wp:attachment":[{"href":"https:\/\/beecare.ch\/de\/wp-json\/wp\/v2\/media?parent=242906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}